{"id":20611,"date":"2025-02-25T09:53:04","date_gmt":"2025-02-25T08:53:04","guid":{"rendered":"https:\/\/pemsa.bisiestodeveloper.es\/?page_id=20611"},"modified":"2025-03-04T09:52:31","modified_gmt":"2025-03-04T08:52:31","slug":"politique-en-matiere-de-cookies","status":"publish","type":"page","link":"https:\/\/www.pemsa-rejiband.com\/fr\/politique-en-matiere-de-cookies\/","title":{"rendered":"Politique en mati\u00e8re de cookies"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\"><strong>POLITIQUE EN MATI\u00c8RE DE COOKIES<\/strong><\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Nous mettons \u00e0 la disposition des utilisateurs la pr\u00e9sente politique en mati\u00e8re de cookies, dans laquelle ils peuvent trouver tous les d\u00e9tails concernant l&rsquo;utilisation des cookies sur notre site web. Nous conseillons aux utilisateurs de consulter fr\u00e9quemment cette politique en mati\u00e8re de cookies, car elle peut \u00eatre mise \u00e0 jour \u00e0 tout moment.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>QUI ?<\/td><td>PEMSA CABLE MANAGEMENT, S.A, avec C.I.F. A-28212181, et si\u00e8ge social \u00e0 Calle Galileo Galilei, 22-24, P.E. La Garena &#8211; 28806 Alcal\u00e1 de Henares (ESPAGNE).<\/td><\/tr><tr><td>QUOI ?<\/td><td>Les cookies sont de petits fichiers install\u00e9s sur l&rsquo;ordinateur de l&rsquo;utilisateur lorsque celui-ci acc\u00e8de \u00e0 un site web.<\/td><\/tr><tr><td>LESQUELS ?<\/td><td>Les types de cookies utilis\u00e9s sur le site web sont les suivants : <a href=\"https:\/\/www.pemsa-rejiband.com\/fr\/politique-en-matiere-de-cookies\/#cookies\" data-type=\"page\" data-id=\"20611\">Tous les cookies<\/a><\/td><\/tr><tr><td>POURQUOI ET POUR QUOI FAIRE ?<\/td><td>Les finalit\u00e9s de chacun des cookies utilis\u00e9s sont les suivantes : <a href=\"https:\/\/www.pemsa-rejiband.com\/fr\/politique-en-matiere-de-cookies\/#cookies\">Tous les cookies<\/a><\/td><\/tr><tr><td>QUAND ?<\/td><td>Vos donn\u00e9es personnelles seront conserv\u00e9es aussi longtemps que n\u00e9cessaire pour atteindre l&rsquo;objectif pour lequel elles ont \u00e9t\u00e9 collect\u00e9es. Dans le cas des cookies qui requi\u00e8rent votre consentement pr\u00e9alable, les donn\u00e9es seront conserv\u00e9es aussi longtemps que vous ne r\u00e9voquerez pas votre consentement.<\/td><\/tr><tr><td>O\u00d9 ?<\/td><td>Le responsable du traitement peut \u00eatre amen\u00e9 \u00e0 transf\u00e9rer vos donn\u00e9es \u00e0 des tiers, lors de l&rsquo;utilisation de cookies de tiers, toujours dans le but d&rsquo;atteindre les objectifs propos\u00e9s. Si, pour quelque raison que ce soit, des transferts internationaux de donn\u00e9es sont effectu\u00e9s en dehors de l&rsquo;Union europ\u00e9enne, vous en serez inform\u00e9 au pr\u00e9alable et votre consentement sera demand\u00e9 \u00e0 cette fin.&nbsp;<\/td><\/tr><tr><td>COMMENT ?<\/td><td>Vous pouvez autoriser ou bloquer les cookies, ainsi que supprimer vos donn\u00e9es de navigation dans le navigateur que vous utilisez. Pour ce faire, consultez les options et les instructions fournies par votre navigateur. Veuillez noter que si vous acceptez les cookies de tiers, vous devez les supprimer dans les options de votre navigateur.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Qui est responsable de vos donn\u00e9es ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est possible que les donn\u00e9es personnelles des utilisateurs soient collect\u00e9es par le biais d&rsquo;un cookie. Le responsable de leur collecte et de leur traitement est PEMSA CABLE MANAGEMENT, S.A., avec C.I.F. A-28212181, et si\u00e8ge social \u00e0 Calle Galileo Galilei, 22-24, P.E. La Garena &#8211; 28806 Alcal\u00e1 de Henares (ESPAGNE).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Qu&rsquo;est-ce qu&rsquo;un biscuit ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les cookies sont de petits fichiers qui s&rsquo;installent sur l&rsquo;ordinateur de l&rsquo;utilisateur lorsque celui-ci acc\u00e8de \u00e0 un site web. Les cookies permettent, entre autres, de stocker et de r\u00e9cup\u00e9rer des informations sur les habitudes de navigation d&rsquo;un utilisateur ou de son \u00e9quipement et, en fonction des informations qu&rsquo;ils contiennent et de la mani\u00e8re dont il utilise son \u00e9quipement, en fonction du type de cookie et des informations qu&rsquo;ils collectent, ils peuvent \u00eatre utilis\u00e9s pour reconna\u00eetre l&rsquo;utilisateur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Types de cookies<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>En fonction de l&rsquo;entit\u00e9 qui g\u00e8re les cookies :<\/li>\n<\/ol>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les propres cookies : ce sont ceux qui sont envoy\u00e9s \u00e0 l&rsquo;appareil ou au terminal de l&rsquo;utilisateur \u00e0 partir de notre \u00e9quipement ou domaine, et qui sont \u00e9galement g\u00e9r\u00e9s par nous-m\u00eames, en tant que propri\u00e9taires et \u00e9diteurs de ce site web.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cookies de tiers : ce sont ceux qui sont envoy\u00e9s \u00e0 l&rsquo;appareil ou au terminal de l&rsquo;utilisateur \u00e0 partir d&rsquo;un ordinateur ou d&rsquo;un domaine qui n&rsquo;est pas g\u00e9r\u00e9 par nous-m\u00eames, mais par un tiers qui traitera les informations obtenues gr\u00e2ce aux cookies.<\/li>\n<\/ul>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li>En fonction de la dur\u00e9e de conservation :<\/li>\n<\/ol>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cookies de session : il s&rsquo;agit de cookies qui collectent et stockent des donn\u00e9es lorsque l&rsquo;utilisateur acc\u00e8de au site web et qui cessent d&rsquo;exister d\u00e8s que l&rsquo;utilisateur quitte le site web.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cookies persistants : il s&rsquo;agit de cookies dont la dur\u00e9e est d\u00e9termin\u00e9e dans le temps par le responsable du traitement des donn\u00e9es. La dur\u00e9e de conservation peut varier de quelques minutes \u00e0 plusieurs ann\u00e9es. Ils sont utilis\u00e9s pour enregistrer et r\u00e9cup\u00e9rer certains param\u00e8tres \u00e0 chaque fois que l&rsquo;utilisateur visite le site web.<\/li>\n<\/ul>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li>En fonction de leur objectif :<\/li>\n<\/ol>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cookies techniques : ils sont essentiels et strictement n\u00e9cessaires au bon fonctionnement du site web et \u00e0 l&rsquo;utilisation des diff\u00e9rentes options ou services que nous proposons. Par exemple, ceux utilis\u00e9s pour maintenir la session, g\u00e9rer le temps de r\u00e9ponse, les performances ou la validation des options, utiliser des \u00e9l\u00e9ments de s\u00e9curit\u00e9, partager des contenus avec les r\u00e9seaux sociaux, etc.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cookies de personnalisation : il s&rsquo;agit de cookies qui permettent \u00e0 l&rsquo;utilisateur de sp\u00e9cifier ou de personnaliser certaines caract\u00e9ristiques du site web. Par exemple, d\u00e9finir la langue, la configuration r\u00e9gionale ou le type de navigateur.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cookies d&rsquo;analyse : ils nous permettent de suivre et d&rsquo;analyser le comportement des utilisateurs sur notre site web afin de cr\u00e9er des profils de navigation et de conna\u00eetre les pr\u00e9f\u00e9rences des utilisateurs. Ils sont g\u00e9n\u00e9ralement utilis\u00e9s pour mesurer l&rsquo;activit\u00e9 des utilisateurs afin d&rsquo;am\u00e9liorer le service que nous offrons en fonction des r\u00e9sultats obtenus. Par exemple, un cookie analytique sera utilis\u00e9 pour surveiller les zones g\u00e9ographiques qui int\u00e9ressent le plus un utilisateur, quel est le produit ou le service le plus populaire, etc.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cookies publicitaires : il s&rsquo;agit de cookies qui nous permettent de g\u00e9rer les espaces publicitaires sur les sites web.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cookies de publicit\u00e9 comportementale : ces cookies permettent de g\u00e9rer les espaces publicitaires sur notre site web. La fonction de ces cookies est de stocker des informations sur le comportement des utilisateurs sur notre site web, afin d&rsquo;afficher par la suite des publicit\u00e9s personnalis\u00e9es.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"cookies\"><strong>Quels sont les cookies que nous utilisons ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plus pr\u00e9cis\u00e9ment, nous utilisons des cookies provenant des tiers suivants aux fins sp\u00e9cifi\u00e9es :<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Cookie<\/td><td>Objectif<\/td><\/tr><tr><td>_ga_WF0VEX656X<br>_gat_gtag_UA_34315975_1<br>Session_5015931<br>_hjSessionUser_5015931<br>_icl_visitor_lang_js<br>wpml_browser_redirect_test<br>OuvertERF<br>nif_validated<br>lang_app<br>s_in_trash<br>ui_info<\/td><td>Cookies propres n\u00e9cessaires \u00e0 l&rsquo;utilisation des options et des services du site web. Ils expirent dans un an.<\/td><\/tr><tr><td>guest_id_ads<br>guest_id_marketing<\/td><td>Cookies n\u00e9cessaires \u00e0 l&rsquo;utilisation des options et services du site web. Ils expirent dans un d\u00e9lai d&rsquo;un an.<br>Comme il est g\u00e9r\u00e9 par Twitter, il est possible que des transferts internationaux de donn\u00e9es aient lieu, c&rsquo;est pourquoi nous avons besoin de votre consentement pour pouvoir les installer.<\/td><\/tr><tr><td>_ga<\/td><td>Utilise l&rsquo;ID pour identifier les utilisateurs. Expire au bout d&rsquo;un an.<br>Ces cookies stockent un identifiant unique afin de vous reconna\u00eetre lors de vos prochaines visites sur le site web. Par cons\u00e9quent, nous avons besoin de votre consentement pour les installer.<\/td><\/tr><tr><td>_gid<\/td><td>ID utilis\u00e9 pour identifier les utilisateurs pendant 24 heures apr\u00e8s la derni\u00e8re activit\u00e9. Il expire au bout de 20 heures.<\/td><\/tr><tr><td>__stid<\/td><td>Le cookie __stid est install\u00e9 dans le cadre du service ShareThis et surveille l&rsquo;activit\u00e9 de l&rsquo;utilisateur, par exemple les pages web visit\u00e9es, la navigation d&rsquo;une page \u00e0 l&rsquo;autre, le temps pass\u00e9 sur chaque page, etc. Il expire au bout de dix mois.<br>Comme il est g\u00e9r\u00e9 par Google, il est possible que des transferts internationaux de donn\u00e9es aient lieu, c&rsquo;est pourquoi nous avons besoin de votre consentement pour pouvoir les installer.<\/td><\/tr><tr><td>guest_id<\/td><td>Ce cookie est mis en place par Twitter pour identifier et suivre le visiteur du site web. Il indique si un utilisateur est connect\u00e9 \u00e0 la plateforme Twitter et recueille des informations sur les pr\u00e9f\u00e9rences publicitaires. Expire dans un an.<br>Comme il est g\u00e9r\u00e9 par Twitter, il est possible que des transferts internationaux de donn\u00e9es aient lieu, c&rsquo;est pourquoi nous avons besoin de votre consentement pour pouvoir les installer.<\/td><\/tr><tr><td>personalization_id<\/td><td>Valeur unique par laquelle les utilisateurs peuvent \u00eatre identifi\u00e9s par Twitter. Les informations collect\u00e9es sont utilis\u00e9es pour personnaliser les services de Twitter, y compris les tendances, les histoires, les publicit\u00e9s et les suggestions de Twitter. Expire dans un an.<br>Comme il est g\u00e9r\u00e9 par Twitter, il est possible que des transferts internationaux de donn\u00e9es aient lieu, c&rsquo;est pourquoi nous avons besoin de votre consentement pour pouvoir les installer.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comment d\u00e9sactiver ou supprimer les cookies ?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le responsable du traitement met \u00e0 la disposition des utilisateurs un panneau de configuration des cookies. Gr\u00e2ce \u00e0 ce panneau, les utilisateurs peuvent accepter ou refuser chacun des cookies pr\u00e9sents sur le site, tant individuellement que collectivement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a class=\"cky-banner-element\">Param\u00e8tres des cookies<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De m\u00eame, l&rsquo;utilisateur peut, \u00e0 tout moment, d\u00e9sactiver ou supprimer les cookies \u00e9num\u00e9r\u00e9s ci-dessus en configurant les options du navigateur utilis\u00e9 sur son appareil ou terminal. L&rsquo;utilisateur doit garder \u00e0 l&rsquo;esprit que s&rsquo;il refuse ou supprime les cookies de navigation du site, nous ne pourrons pas conserver ses pr\u00e9f\u00e9rences et certaines fonctionnalit\u00e9s du site ne seront pas op\u00e9rationnelles, de sorte que nous ne pourrons pas lui offrir des services personnalis\u00e9s et qu&rsquo;\u00e0 chaque fois qu&rsquo;il naviguera sur notre site, nous devrons lui demander \u00e0 nouveau l&rsquo;autorisation d&rsquo;utiliser des cookies.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous trouverez ci-dessous des liens vers des informations sur la mani\u00e8re d&rsquo;activer vos pr\u00e9f\u00e9rences dans les principaux navigateurs :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/support.google.com\/chrome\/bin\/answer.py?hl=es&amp;answer=95647\">Param\u00e8tres des cookies pour Google Chrome<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/support.mozilla.org\/es\/kb\/cookies-informacion-que-los-sitios-web-guardan-en-?redirectlocale=en-US&amp;redirectslug=Cookies\">Param\u00e8tres des cookies pour Mozilla Firefox<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/support.microsoft.com\/kb\/196955\/es\">Param\u00e8tres des cookies pour Internet Explorer<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/support.apple.com\/kb\/HT1677?viewlocale=es_ES\">Param\u00e8tres des cookies pour Safari<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 qui vos donn\u00e9es seront-elles communiqu\u00e9es ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En g\u00e9n\u00e9ral, les donn\u00e9es des utilisateurs collect\u00e9es par le biais de cookies sur ce site web ne seront pas transf\u00e9r\u00e9es \u00e0 des tiers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toutefois, si \u00e0 un moment donn\u00e9 des cookies g\u00e9r\u00e9s par des tiers devaient \u00eatre utilis\u00e9s sur ce site web, ce qui pourrait impliquer des transferts internationaux de donn\u00e9es en dehors de l&rsquo;Union europ\u00e9enne, l&rsquo;utilisateur en serait inform\u00e9 au pr\u00e9alable et le consentement appropri\u00e9 lui serait demand\u00e9.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Profilage ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous vous informons \u00e9galement que le responsable n&rsquo;a pas l&rsquo;intention d&rsquo;effectuer un profilage avec les donn\u00e9es collect\u00e9es par le biais des cookies utilis\u00e9s sur le site web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si elles devaient \u00eatre mises en \u0153uvre \u00e0 l&rsquo;avenir, les utilisateurs en seraient inform\u00e9s \u00e0 l&rsquo;avance et leur consentement serait demand\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Plus d&rsquo;informations<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez des questions sur la mani\u00e8re dont nous utilisons les cookies et que vous ne trouvez pas de r\u00e9ponse dans la pr\u00e9sente politique en mati\u00e8re de cookies, veuillez nous envoyer vos commentaires par courrier \u00e9lectronique \u00e0 l&rsquo;adresse suivante : info@pemsa-rejiband.com.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous souhaitez obtenir de plus amples informations sur l&rsquo;utilisation des cookies par les sites web, vous pouvez consulter la <a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2002-13758\">la loi 34\/2002, du 11 juillet, sur les services de la soci\u00e9t\u00e9 de l&rsquo;information et du commerce \u00e9lectronique<\/a> et le <a href=\"https:\/\/www.agpd.es\/portalwebAGPD\/canaldocumentacion\/publicaciones\/common\/Guias\/Guia_Cookies.pdf\">Guide sur l&rsquo;utilisation des cookies publi\u00e9 par l&rsquo;Agence de protection des donn\u00e9es.<\/a>.<br>Vous pouvez \u00e9galement consulter la page <a href=\"http:\/\/www.youronlinechoices.com\/es\/\">Vos en lignechoix <\/a>&nbsp;o\u00f9, en plus de trouver des informations utiles, vous pouvez d\u00e9finir vos pr\u00e9f\u00e9rences en mati\u00e8re de cookies publicitaires tiers, fournisseur par fournisseur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>POLITIQUE EN MATI\u00c8RE DE COOKIES Nous mettons \u00e0 la disposition des utilisateurs la pr\u00e9sente politique en mati\u00e8re de cookies, dans laquelle ils peuvent trouver tous les d\u00e9tails concernant l&rsquo;utilisation des cookies sur notre site web. Nous conseillons aux utilisateurs de consulter fr\u00e9quemment cette politique en mati\u00e8re de cookies, car elle peut \u00eatre mise \u00e0 jour [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-legales.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-20611","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique en mati\u00e8re de cookies - Pemsa Cable Management Systems<\/title>\n<meta name=\"description\" content=\"L\u00edderes en sistemas de conducci\u00f3n de cables.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pemsa-rejiband.com\/fr\/politique-en-matiere-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique en mati\u00e8re de cookies - Pemsa Cable Management Systems\" \/>\n<meta property=\"og:description\" content=\"L\u00edderes en sistemas de conducci\u00f3n de cables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pemsa-rejiband.com\/fr\/politique-en-matiere-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"Pemsa Cable Management Systems\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PemsaCableManagementSystem\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-04T08:52:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pemsa-rejiband.com\/wp-content\/uploads\/2025\/03\/Logo-PEMSA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"348\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PemsaRejiband\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/fr\\\/politique-en-matiere-de-cookies\\\/\",\"url\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/fr\\\/politique-en-matiere-de-cookies\\\/\",\"name\":\"Politique en mati\u00e8re de cookies - Pemsa Cable Management Systems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/#website\"},\"datePublished\":\"2025-02-25T08:53:04+00:00\",\"dateModified\":\"2025-03-04T08:52:31+00:00\",\"description\":\"L\u00edderes en sistemas de conducci\u00f3n de cables.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/fr\\\/politique-en-matiere-de-cookies\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pemsa-rejiband.com\\\/fr\\\/politique-en-matiere-de-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/fr\\\/politique-en-matiere-de-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique en mati\u00e8re de cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/#website\",\"url\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/\",\"name\":\"Pemsa Cable Management Systems\",\"description\":\"Bandejas portacables y sistemas de tubos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/#organization\",\"name\":\"Pemsa Cable Management Systems\",\"url\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/logo-pemsa.svg\",\"contentUrl\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/logo-pemsa.svg\",\"caption\":\"Pemsa Cable Management Systems\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pemsa-rejiband.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PemsaCableManagementSystem\\\/\",\"https:\\\/\\\/x.com\\\/PemsaRejiband\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pemsa\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique en mati\u00e8re de cookies - Pemsa Cable Management Systems","description":"L\u00edderes en sistemas de conducci\u00f3n de cables.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pemsa-rejiband.com\/fr\/politique-en-matiere-de-cookies\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique en mati\u00e8re de cookies - Pemsa Cable Management Systems","og_description":"L\u00edderes en sistemas de conducci\u00f3n de cables.","og_url":"https:\/\/www.pemsa-rejiband.com\/fr\/politique-en-matiere-de-cookies\/","og_site_name":"Pemsa Cable Management Systems","article_publisher":"https:\/\/www.facebook.com\/PemsaCableManagementSystem\/","article_modified_time":"2025-03-04T08:52:31+00:00","og_image":[{"width":1920,"height":348,"url":"https:\/\/www.pemsa-rejiband.com\/wp-content\/uploads\/2025\/03\/Logo-PEMSA.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@PemsaRejiband","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pemsa-rejiband.com\/fr\/politique-en-matiere-de-cookies\/","url":"https:\/\/www.pemsa-rejiband.com\/fr\/politique-en-matiere-de-cookies\/","name":"Politique en mati\u00e8re de cookies - Pemsa Cable Management Systems","isPartOf":{"@id":"https:\/\/www.pemsa-rejiband.com\/#website"},"datePublished":"2025-02-25T08:53:04+00:00","dateModified":"2025-03-04T08:52:31+00:00","description":"L\u00edderes en sistemas de conducci\u00f3n de cables.","breadcrumb":{"@id":"https:\/\/www.pemsa-rejiband.com\/fr\/politique-en-matiere-de-cookies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pemsa-rejiband.com\/fr\/politique-en-matiere-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pemsa-rejiband.com\/fr\/politique-en-matiere-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.pemsa-rejiband.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Politique en mati\u00e8re de cookies"}]},{"@type":"WebSite","@id":"https:\/\/www.pemsa-rejiband.com\/#website","url":"https:\/\/www.pemsa-rejiband.com\/","name":"Pemsa Cable Management Systems","description":"Bandejas portacables y sistemas de tubos","publisher":{"@id":"https:\/\/www.pemsa-rejiband.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pemsa-rejiband.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.pemsa-rejiband.com\/#organization","name":"Pemsa Cable Management Systems","url":"https:\/\/www.pemsa-rejiband.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.pemsa-rejiband.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.pemsa-rejiband.com\/wp-content\/uploads\/2024\/12\/logo-pemsa.svg","contentUrl":"https:\/\/www.pemsa-rejiband.com\/wp-content\/uploads\/2024\/12\/logo-pemsa.svg","caption":"Pemsa Cable Management Systems"},"image":{"@id":"https:\/\/www.pemsa-rejiband.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PemsaCableManagementSystem\/","https:\/\/x.com\/PemsaRejiband","https:\/\/www.linkedin.com\/company\/pemsa\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.pemsa-rejiband.com\/fr\/wp-json\/wp\/v2\/pages\/20611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pemsa-rejiband.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pemsa-rejiband.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pemsa-rejiband.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pemsa-rejiband.com\/fr\/wp-json\/wp\/v2\/comments?post=20611"}],"version-history":[{"count":2,"href":"https:\/\/www.pemsa-rejiband.com\/fr\/wp-json\/wp\/v2\/pages\/20611\/revisions"}],"predecessor-version":[{"id":25223,"href":"https:\/\/www.pemsa-rejiband.com\/fr\/wp-json\/wp\/v2\/pages\/20611\/revisions\/25223"}],"wp:attachment":[{"href":"https:\/\/www.pemsa-rejiband.com\/fr\/wp-json\/wp\/v2\/media?parent=20611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}